{"id":9653,"date":"2021-01-19T22:17:21","date_gmt":"2021-01-19T21:17:21","guid":{"rendered":"https:\/\/triana.salesianos.edu\/colegio\/?p=9653"},"modified":"2021-01-24T13:47:44","modified_gmt":"2021-01-24T12:47:44","slug":"estrenamos-espacio-web","status":"publish","type":"post","link":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2021\/01\/19\/estrenamos-espacio-web\/","title":{"rendered":"Estrenamos espacio web"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Nadie puede negar hoy en d\u00eda la importancia de la comunicaci\u00f3n. Y m\u00e1s a\u00fan en el mundo que vivimos altamente digitalizado. Por eso, en los \u00faltimos meses la AMPA est\u00e1 haciendo un esfuerzo por estar presente en aquellos medios que pueden ser accesibles a sus asociados.<\/p>\n<p>Ya desde hace tiempo estamos presentes en las redes sociales con perfiles de Twiter y Facebook. Posteriormente abrimos la cuenta de Instagram. Este curso escolar hemos comenzado a editar y difundir un bolet\u00edn mensual de noticias, que se remite v\u00eda Qualitas Educativa a todos los padres y madres o tutores legales de los alumnos del colegio.<\/p>\n<p>Con este art\u00edculo inauguramos un nuevo medio, una nueva v\u00eda, para estar cerca de los asociados y de todos los interesados en nuestra actividad como AMPA: estrenamos este espacio web dentro de la p\u00e1gina web del colegio.<\/p>\n<p>Pretendemos que este espacio facilite la posibilidad de acceder a la informaci\u00f3n m\u00e1s actual sobre nuestra AMPA: actividades, convocatorias, acciones, \u2026<\/p>\n<p>Adem\u00e1s, hemos propuesto que este estreno sea el 24 de enero, festividad de San Francisco de Sales. Y ello se debe a un doble motivo:<br \/>\nPor un lado, porque cuando Don Bosco fund\u00f3 la congregaci\u00f3n salesiana se inspir\u00f3 en San Francisco de Sales, en su base carism\u00e1tica de caridad y dulzura que son dos grandes cimientos de esta congregaci\u00f3n. De \u00e9l proviene el nombre de Salesianos.<br \/>\nY, por otro lado, porque San Francisco de Sales es el patrono de los periodistas y escritores ya que destac\u00f3, como se deduce, por su gran capacidad comunicativa a trav\u00e9s de la escritura. Cuando P\u00edo XI canoniz\u00f3 a San Francisco de Sales destac\u00f3 que es necesario que los periodistas \u00abimiten y muestren en todo momento que el rigor siempre ha estado unido a la moderaci\u00f3n y la caridad, que era la caracter\u00edstica especial de San Francisco\u00bb<\/p>\n<p>Esperamos que este nuevo medio concite vuestro inter\u00e9s y que de manera peri\u00f3dica pod\u00e1is acudir a la web para estar informados de todo lo que acontece en la AMPA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un elemento m\u00e1s de comunicaci\u00f3n con nuestros asociados<\/p>\n","protected":false},"author":5,"featured_media":9654,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-9653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ampa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estrenamos espacio web - Colegio Salesiano San Pedro<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estrenamos espacio web - Colegio Salesiano San Pedro\" \/>\n<meta property=\"og:description\" content=\"Un elemento m\u00e1s de comunicaci\u00f3n con nuestros asociados\" \/>\n<meta property=\"og:url\" content=\"https:\/\/triana.salesianos.edu\/colegio\/blog\/2021\/01\/19\/estrenamos-espacio-web\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Salesiano San Pedro\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-19T21:17:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-24T12:47:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/01\/website.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"david\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"david\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/01\\\/19\\\/estrenamos-espacio-web\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/01\\\/19\\\/estrenamos-espacio-web\\\/\"},\"author\":{\"name\":\"david\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/f19e32115388f0564d5bead444a05d00\"},\"headline\":\"Estrenamos espacio web\",\"datePublished\":\"2021-01-19T21:17:21+00:00\",\"dateModified\":\"2021-01-24T12:47:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/01\\\/19\\\/estrenamos-espacio-web\\\/\"},\"wordCount\":354,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/01\\\/19\\\/estrenamos-espacio-web\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/website.png\",\"articleSection\":[\"AMPA\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/01\\\/19\\\/estrenamos-espacio-web\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/01\\\/19\\\/estrenamos-espacio-web\\\/\",\"url\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/01\\\/19\\\/estrenamos-espacio-web\\\/\",\"name\":\"Estrenamos espacio web - Colegio Salesiano San Pedro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/01\\\/19\\\/estrenamos-espacio-web\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/01\\\/19\\\/estrenamos-espacio-web\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/website.png\",\"datePublished\":\"2021-01-19T21:17:21+00:00\",\"dateModified\":\"2021-01-24T12:47:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/f19e32115388f0564d5bead444a05d00\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/01\\\/19\\\/estrenamos-espacio-web\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/01\\\/19\\\/estrenamos-espacio-web\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/01\\\/19\\\/estrenamos-espacio-web\\\/#primaryimage\",\"url\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/website.png\",\"contentUrl\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/website.png\",\"width\":1280,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/01\\\/19\\\/estrenamos-espacio-web\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estrenamos espacio web\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Salesiano San Pedro\",\"description\":\"P\u00e1gina oficial Salesianos Triana Sevilla\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/f19e32115388f0564d5bead444a05d00\",\"name\":\"david\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33bb1a691c2e3f2585e0eb725819ad668b28a17e6dc982fb9be10daf15918368?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33bb1a691c2e3f2585e0eb725819ad668b28a17e6dc982fb9be10daf15918368?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33bb1a691c2e3f2585e0eb725819ad668b28a17e6dc982fb9be10daf15918368?s=96&d=mm&r=g\",\"caption\":\"david\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estrenamos espacio web - Colegio Salesiano San Pedro","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Estrenamos espacio web - Colegio Salesiano San Pedro","og_description":"Un elemento m\u00e1s de comunicaci\u00f3n con nuestros asociados","og_url":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2021\/01\/19\/estrenamos-espacio-web\/","og_site_name":"Colegio Salesiano San Pedro","article_published_time":"2021-01-19T21:17:21+00:00","article_modified_time":"2021-01-24T12:47:44+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/01\/website.png","type":"image\/png"}],"author":"david","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"david","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2021\/01\/19\/estrenamos-espacio-web\/#article","isPartOf":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2021\/01\/19\/estrenamos-espacio-web\/"},"author":{"name":"david","@id":"https:\/\/triana.salesianos.edu\/colegio\/#\/schema\/person\/f19e32115388f0564d5bead444a05d00"},"headline":"Estrenamos espacio web","datePublished":"2021-01-19T21:17:21+00:00","dateModified":"2021-01-24T12:47:44+00:00","mainEntityOfPage":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2021\/01\/19\/estrenamos-espacio-web\/"},"wordCount":354,"commentCount":0,"image":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2021\/01\/19\/estrenamos-espacio-web\/#primaryimage"},"thumbnailUrl":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/01\/website.png","articleSection":["AMPA"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/triana.salesianos.edu\/colegio\/blog\/2021\/01\/19\/estrenamos-espacio-web\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2021\/01\/19\/estrenamos-espacio-web\/","url":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2021\/01\/19\/estrenamos-espacio-web\/","name":"Estrenamos espacio web - Colegio Salesiano San Pedro","isPartOf":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2021\/01\/19\/estrenamos-espacio-web\/#primaryimage"},"image":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2021\/01\/19\/estrenamos-espacio-web\/#primaryimage"},"thumbnailUrl":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/01\/website.png","datePublished":"2021-01-19T21:17:21+00:00","dateModified":"2021-01-24T12:47:44+00:00","author":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/#\/schema\/person\/f19e32115388f0564d5bead444a05d00"},"breadcrumb":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2021\/01\/19\/estrenamos-espacio-web\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/triana.salesianos.edu\/colegio\/blog\/2021\/01\/19\/estrenamos-espacio-web\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2021\/01\/19\/estrenamos-espacio-web\/#primaryimage","url":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/01\/website.png","contentUrl":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/01\/website.png","width":1280,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2021\/01\/19\/estrenamos-espacio-web\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/triana.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Estrenamos espacio web"}]},{"@type":"WebSite","@id":"https:\/\/triana.salesianos.edu\/colegio\/#website","url":"https:\/\/triana.salesianos.edu\/colegio\/","name":"Colegio Salesiano San Pedro","description":"P\u00e1gina oficial Salesianos Triana Sevilla","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/triana.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/triana.salesianos.edu\/colegio\/#\/schema\/person\/f19e32115388f0564d5bead444a05d00","name":"david","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/33bb1a691c2e3f2585e0eb725819ad668b28a17e6dc982fb9be10daf15918368?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/33bb1a691c2e3f2585e0eb725819ad668b28a17e6dc982fb9be10daf15918368?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/33bb1a691c2e3f2585e0eb725819ad668b28a17e6dc982fb9be10daf15918368?s=96&d=mm&r=g","caption":"david"}}]}},"_links":{"self":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/9653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=9653"}],"version-history":[{"count":1,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/9653\/revisions"}],"predecessor-version":[{"id":9655,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/9653\/revisions\/9655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/9654"}],"wp:attachment":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=9653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=9653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=9653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}