{"id":9110,"date":"2020-04-29T12:52:45","date_gmt":"2020-04-29T10:55:24","guid":{"rendered":"https:\/\/triana.salesianos.edu\/colegio\/?p=9110"},"modified":"2023-11-29T10:35:58","modified_gmt":"2023-11-29T09:35:58","slug":"profesencuarentena-hoy-conocemos-a-juani","status":"publish","type":"post","link":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/04\/29\/profesencuarentena-hoy-conocemos-a-juani\/","title":{"rendered":"#ProfesEnCuarentena Hoy conocemos a&#8230;Juani"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb3.22&#8243;][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb3.25&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbEntradilla (Texto)\u00bb _builder_version=\u00bb4.3.4&#8243; text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; border_style=\u00bbsolid\u00bb]<\/p>\n<p><strong><em>Comenzamos una serie de entrevistas para conocer c\u00f3mo est\u00e1n viviendo algunos profesores esta situaci\u00f3n de confinamiento. Esta semana, conocemos a Juani Garc\u00eda Fern\u00e1ndez, profesora de Educaci\u00f3n Infantil, en este curso con los chicos de 3 a\u00f1os.<\/em><\/strong><\/p>\n<p><!--more--><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.3.4&#8243; text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; border_style=\u00bbsolid\u00bb]<\/p>\n<p><em><strong>\u00bfQu\u00ed\u00e9n es Juani Garc\u00eda?<\/strong><\/em><\/p>\n<p>Soy Juani, nac\u00ed en sevilla y me cri\u00e9 entre Triana y Carmona, ya que mis padres son de all\u00ed y todos los fines de semana y fiestas de guardar nos \u00edbamos para all\u00e1. Yo estudi\u00e9 en el Colegio Protectorado de la Infancia, del que guardo muy buenos recuerdos y cuando termin\u00e9 8\u00ba de e.g.b. tuve la suerte de entrar en nuestro cole y formar parte de la primera promoci\u00f3n mixta del B.U.P. Ni que decir tiene lo requetebi\u00e9n que me lo pas\u00e9 en el cole y lo contenta que yo iba a diario a encontrarme con los\/as compa\u00f1eros\/as. S\u00ed que aprend\u00ed\u00a0 y forj\u00e9 mi vocaci\u00f3n en estos a\u00f1os. La persona que soy ahora es gracias a muchos de los factores que en estos a\u00f1os se fueron dando en mi vida<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb3_5,2_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.3.4&#8243; text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; border_style=\u00bbsolid\u00bb]<\/p>\n<p><em><strong>\u00bfTienes alg\u00fan hobby o afici\u00f3n que quieras compartir?<\/strong><\/em><\/p>\n<p class=\"Cuerpodetexto\">Me encanta pasar tiempo con la familia, tener siempre cerca a alguno de mis sobrinos\/as. Otro hobby es hacer visitas culturales. Pero sobre todo lo que mas me gusta es dedicar alg\u00fan momento del d\u00eda para leer un ratillo en mi sill\u00f3n.<\/p>\n<p class=\"Cuerpodetexto\"><em><strong>\u00bfPodr\u00edas decir algo que sorprenda sobre tu forma de ser o alguna habilidad que tengas?<\/strong><\/em><\/p>\n<p class=\"Cuerpodetexto\">Intento estar siempre alegre y no desesperar. Me tomo las cosas con calma para poder atender bien a todo el mundo y cumplir con todos mis quehaceres.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_image _builder_version=\u00bb4.3.4&#8243; src=\u00bbhttps:\/\/triana.salesianos.edu\/wp-content\/uploads\/2020\/04\/20200415_185937.jpg\u00bb hover_enabled=\u00bb0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.0.6&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.3.4&#8243; text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; border_style=\u00bbsolid\u00bb]<\/p>\n<p><em><strong>\u00bfQu\u00e9 echas de menos en este tiempo de confinamiento?<\/strong><\/em><\/p>\n<p class=\"Cuerpodetexto\">Llevo muy mal lo de no ver a los seres queridos, no dar besos ni abrazos. No pisar la calle, no oler el azahar de estos d\u00edas, no tener la libertad para hacer lo que quiera en cada momento.<\/p>\n<p><em><strong>\u00bfA qu\u00e9 dedicas el tiempo libre en casa?<\/strong><\/em><\/p>\n<p>\u00a1\u00a1No me queda tiempo libre!! No paro de inventarme cosas. Cuando termino de teletrabajar, juego un poco a las casitas: lo de diario, vamos, que hay que hacer de todo. En otros momentos me pongo a ordenar los armarios, a sacar cajones y reorganizarlos\u2026.he hecho hasta croquetas y torrijas que no las hab\u00eda hecho antes, siempre ten\u00eda a mi hermana que las hac\u00eda<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb2_5,3_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_image src=\u00bbhttps:\/\/triana.salesianos.edu\/wp-content\/uploads\/2020\/04\/20200415_201355-1.jpg\u00bb _builder_version=\u00bb4.3.4&#8243; hover_enabled=\u00bb0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.3.4&#8243; text_orientation=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; border_style=\u00bbsolid\u00bb]<\/p>\n<p><em><strong>\u00bfCu\u00e1l es tu recorrido como profesor\/a en los Salesianos de Triana?<\/strong><\/em><\/p>\n<p>Llevo ya trabajando en el cole 17 a\u00f1os , siempre he estado en Infantil y espero jubilarme en la misma etapa. Desde adolescente he estado vinculada a los grupos de fe y todos los viernes echaba la tarde en el cole, bien como animadora, bien como animanda. Me encantaba que llegaran los veranos para irme de campamento y a los 17 a\u00f1os me fui a colaborar en la Parroquia de Jes\u00fas Obrero y alli era donde pasaba los fines de semana, entre los grupos de fe y el oratorio \u201cEl Cotarro\u201d<\/p>\n<p><em><strong>\u00bfPor qu\u00e9 elegiste ser profesor\/a?<\/strong><\/em><\/p>\n<p>Por vocaci\u00f3n. Desde peque\u00f1a ten\u00eda muy claro que quer\u00eda ser madre (siempre que me preguntaban que quer\u00eda ser de mayor dec\u00eda que quer\u00eda ser madre) . As\u00ed que siempre fui encaminando mi vida para dedicarme a la educaci\u00f3n.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.3.4&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.3.4&#8243;][et_pb_text _builder_version=\u00bb4.3.4&#8243; hover_enabled=\u00bb0&#8243;]<\/p>\n<p><em><strong>\u00bfPor qu\u00e9 de Infantil?<\/strong><\/em><\/p>\n<p>Porque considero la etapa mas bonita de la vida. En la que empiezas a descubrir, a conocer, a preguntar, a interactuar con el mundo\u2026 porque es un momento de aprendizaje donde el ni\u00f1o adquiere las capacidades b\u00e1sicas para abrirse camino en este mundo.<\/p>\n<p><em><strong>Si no hubieses sido profesora \u00bfqu\u00e9 te habr\u00eda gustado ser?<\/strong><\/em><\/p>\n<p>Pues\u2026\u2026educadora social, no ten\u00eda clara muchas opciones<\/p>\n<p><em><strong>En este tiempo de cuarentena estamos viviendo la ense\u00f1anza de una manera que no hab\u00edamos vivido nunca, \u00bfqu\u00e9 crees que vamos a sacar de positivo para nuestra labor?<\/strong><\/em><\/p>\n<p>Valorar la cercan\u00eda con las personas, la importancia d estar presente, de compartir y sentirnos uno.<\/p>\n<p><em><strong>Por \u00faltimo, \u00bftienes alguna an\u00e9cdota que recuerdes con cari\u00f1o como profesor\/a del colegio?<\/strong><\/em><\/p>\n<p>An\u00e9cdotas muchas, casi a diario. La etapa en la que me encuentro da mucho juego para esto de las an\u00e9cdotas. Pero me gustar\u00eda compartir que lo mejor que me puede pasar a diario es llegar al cole y encontrarme con mis alumn@s y que cuando estamos en silencio y concentrados \u2026.salte uno diciendo: \u201cse\u00f1o, que guapa est\u00e1s hoy\u201d, \u201cqu\u00e9 me gusta tu rebeca\u201d, y si no\u2026cuando salen corriendo a darte un beso. Esta sensaci\u00f3n de cari\u00f1o, de gratitud, de\u2026esto es lo que me recompensa cada d\u00eda.\u00a0<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.3.4&#8243; column_structure=\u00bb1_2,1_2&#8243;][et_pb_column _builder_version=\u00bb4.3.4&#8243; type=\u00bb1_2&#8243;][et_pb_image src=\u00bbhttps:\/\/triana.salesianos.edu\/wp-content\/uploads\/2020\/04\/20200415_190812.jpg\u00bb _builder_version=\u00bb4.3.4&#8243; hover_enabled=\u00bb0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column _builder_version=\u00bb4.3.4&#8243; type=\u00bb1_2&#8243;][et_pb_image _builder_version=\u00bb4.3.4&#8243; src=\u00bbhttps:\/\/triana.salesianos.edu\/wp-content\/uploads\/2020\/04\/20200415_201345.jpg\u00bb hover_enabled=\u00bb0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comenzamos una serie de entrevistas para conocer c\u00f3mo est\u00e1n viviendo algunos profesores esta situaci\u00f3n de confinamiento. Esta semana, conocemos a Juani Garc\u00eda Fern\u00e1ndez, profesora de Educaci\u00f3n Infantil, en este curso con los chicos de 3 a\u00f1os. \u00bfQu\u00ed\u00e9n es Juani Garc\u00eda? Soy Juani, nac\u00ed en sevilla y me cri\u00e9 entre Triana y Carmona, ya que mis [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9107,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[27,14,16],"tags":[],"class_list":["post-9110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colegio","category-infantil","category-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#ProfesEnCuarentena Hoy conocemos a&#8230;Juani - Colegio Salesiano San Pedro<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#ProfesEnCuarentena Hoy conocemos a&#8230;Juani - Colegio Salesiano San Pedro\" \/>\n<meta property=\"og:description\" content=\"Comenzamos una serie de entrevistas para conocer c\u00f3mo est\u00e1n viviendo algunos profesores esta situaci\u00f3n de confinamiento. Esta semana, conocemos a Juani Garc\u00eda Fern\u00e1ndez, profesora de Educaci\u00f3n Infantil, en este curso con los chicos de 3 a\u00f1os. \u00bfQu\u00ed\u00e9n es Juani Garc\u00eda? Soy Juani, nac\u00ed en sevilla y me cri\u00e9 entre Triana y Carmona, ya que mis [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/04\/29\/profesencuarentena-hoy-conocemos-a-juani\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Salesiano San Pedro\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-29T10:55:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-29T09:35:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/04\/20200415_201407.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1027\" \/>\n\t<meta property=\"og:image:height\" content=\"777\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestor Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestor Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/04\\\/29\\\/profesencuarentena-hoy-conocemos-a-juani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/04\\\/29\\\/profesencuarentena-hoy-conocemos-a-juani\\\/\"},\"author\":{\"name\":\"Gestor Web\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac56d09b53320706efba5d42fa54fa77\"},\"headline\":\"#ProfesEnCuarentena Hoy conocemos a&#8230;Juani\",\"datePublished\":\"2020-04-29T10:55:24+00:00\",\"dateModified\":\"2023-11-29T09:35:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/04\\\/29\\\/profesencuarentena-hoy-conocemos-a-juani\\\/\"},\"wordCount\":1153,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/04\\\/29\\\/profesencuarentena-hoy-conocemos-a-juani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/20200415_201407.jpg\",\"articleSection\":[\"Colegio\",\"Infantil\",\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/04\\\/29\\\/profesencuarentena-hoy-conocemos-a-juani\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/04\\\/29\\\/profesencuarentena-hoy-conocemos-a-juani\\\/\",\"url\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/04\\\/29\\\/profesencuarentena-hoy-conocemos-a-juani\\\/\",\"name\":\"#ProfesEnCuarentena Hoy conocemos a&#8230;Juani - Colegio Salesiano San Pedro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/04\\\/29\\\/profesencuarentena-hoy-conocemos-a-juani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/04\\\/29\\\/profesencuarentena-hoy-conocemos-a-juani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/20200415_201407.jpg\",\"datePublished\":\"2020-04-29T10:55:24+00:00\",\"dateModified\":\"2023-11-29T09:35:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac56d09b53320706efba5d42fa54fa77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/04\\\/29\\\/profesencuarentena-hoy-conocemos-a-juani\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/04\\\/29\\\/profesencuarentena-hoy-conocemos-a-juani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/04\\\/29\\\/profesencuarentena-hoy-conocemos-a-juani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/20200415_201407.jpg\",\"contentUrl\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/20200415_201407.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/04\\\/29\\\/profesencuarentena-hoy-conocemos-a-juani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#ProfesEnCuarentena Hoy conocemos a&#8230;Juani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Salesiano San Pedro\",\"description\":\"P\u00e1gina oficial Salesianos Triana Sevilla\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac56d09b53320706efba5d42fa54fa77\",\"name\":\"Gestor Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g\",\"caption\":\"Gestor Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#ProfesEnCuarentena Hoy conocemos a&#8230;Juani - Colegio Salesiano San Pedro","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"#ProfesEnCuarentena Hoy conocemos a&#8230;Juani - Colegio Salesiano San Pedro","og_description":"Comenzamos una serie de entrevistas para conocer c\u00f3mo est\u00e1n viviendo algunos profesores esta situaci\u00f3n de confinamiento. Esta semana, conocemos a Juani Garc\u00eda Fern\u00e1ndez, profesora de Educaci\u00f3n Infantil, en este curso con los chicos de 3 a\u00f1os. \u00bfQu\u00ed\u00e9n es Juani Garc\u00eda? Soy Juani, nac\u00ed en sevilla y me cri\u00e9 entre Triana y Carmona, ya que mis [&hellip;]","og_url":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/04\/29\/profesencuarentena-hoy-conocemos-a-juani\/","og_site_name":"Colegio Salesiano San Pedro","article_published_time":"2020-04-29T10:55:24+00:00","article_modified_time":"2023-11-29T09:35:58+00:00","og_image":[{"width":1027,"height":777,"url":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/04\/20200415_201407.jpg","type":"image\/jpeg"}],"author":"Gestor Web","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gestor Web","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/04\/29\/profesencuarentena-hoy-conocemos-a-juani\/#article","isPartOf":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/04\/29\/profesencuarentena-hoy-conocemos-a-juani\/"},"author":{"name":"Gestor Web","@id":"https:\/\/triana.salesianos.edu\/colegio\/#\/schema\/person\/ac56d09b53320706efba5d42fa54fa77"},"headline":"#ProfesEnCuarentena Hoy conocemos a&#8230;Juani","datePublished":"2020-04-29T10:55:24+00:00","dateModified":"2023-11-29T09:35:58+00:00","mainEntityOfPage":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/04\/29\/profesencuarentena-hoy-conocemos-a-juani\/"},"wordCount":1153,"commentCount":0,"image":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/04\/29\/profesencuarentena-hoy-conocemos-a-juani\/#primaryimage"},"thumbnailUrl":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/04\/20200415_201407.jpg","articleSection":["Colegio","Infantil","Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/04\/29\/profesencuarentena-hoy-conocemos-a-juani\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/04\/29\/profesencuarentena-hoy-conocemos-a-juani\/","url":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/04\/29\/profesencuarentena-hoy-conocemos-a-juani\/","name":"#ProfesEnCuarentena Hoy conocemos a&#8230;Juani - Colegio Salesiano San Pedro","isPartOf":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/04\/29\/profesencuarentena-hoy-conocemos-a-juani\/#primaryimage"},"image":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/04\/29\/profesencuarentena-hoy-conocemos-a-juani\/#primaryimage"},"thumbnailUrl":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/04\/20200415_201407.jpg","datePublished":"2020-04-29T10:55:24+00:00","dateModified":"2023-11-29T09:35:58+00:00","author":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/#\/schema\/person\/ac56d09b53320706efba5d42fa54fa77"},"breadcrumb":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/04\/29\/profesencuarentena-hoy-conocemos-a-juani\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/04\/29\/profesencuarentena-hoy-conocemos-a-juani\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/04\/29\/profesencuarentena-hoy-conocemos-a-juani\/#primaryimage","url":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/04\/20200415_201407.jpg","contentUrl":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/04\/20200415_201407.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/04\/29\/profesencuarentena-hoy-conocemos-a-juani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/triana.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"#ProfesEnCuarentena Hoy conocemos a&#8230;Juani"}]},{"@type":"WebSite","@id":"https:\/\/triana.salesianos.edu\/colegio\/#website","url":"https:\/\/triana.salesianos.edu\/colegio\/","name":"Colegio Salesiano San Pedro","description":"P\u00e1gina oficial Salesianos Triana Sevilla","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/triana.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/triana.salesianos.edu\/colegio\/#\/schema\/person\/ac56d09b53320706efba5d42fa54fa77","name":"Gestor Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g","caption":"Gestor Web"}}]}},"_links":{"self":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/9110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=9110"}],"version-history":[{"count":1,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/9110\/revisions"}],"predecessor-version":[{"id":9111,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/9110\/revisions\/9111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/9107"}],"wp:attachment":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=9110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=9110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=9110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}