{"id":9074,"date":"2020-03-05T20:27:13","date_gmt":"2020-03-05T19:27:25","guid":{"rendered":"https:\/\/triana.salesianos.edu\/colegio\/?p=9074"},"modified":"2023-11-29T10:36:02","modified_gmt":"2023-11-29T09:36:02","slug":"infantil-aprende-jugando","status":"publish","type":"post","link":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/03\/05\/infantil-aprende-jugando\/","title":{"rendered":"Infantil aprende jugando"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb3.22&#8243;][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb3.25&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbEntradilla (Texto)\u00bb _builder_version=\u00bb4.3.4&#8243; text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb border_style=\u00bbsolid\u00bb]<\/p>\n<p><em><strong>En nuestro colegio creemos que nuestra escuela debe buscar la forma de contribuir a que el mundo en el que vivimos sea un lugar m\u00e1s justo y sostenible. Por eso en la etapa de Educaci\u00f3n Infantil estamos desarrollando un programa que se llama \u201c\u00c9rase una vez una escuela para el Mundo\u201d en colaboraci\u00f3n con la ONGD BoscoGlobal.<\/strong><\/em><\/p>\n<p><!--more--><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.3.4&#8243; text_orientation=\u00bbjustified\u00bb border_style=\u00bbsolid\u00bb]<\/p>\n<p>Este programa, entre otras acciones, est\u00e1 llevando adelante con el alumnado de Infantil un <strong>proyecto educativo que tiene como centro de inter\u00e9s \u201cEl juego\u201d. <\/strong>Adem\u00e1s, se est\u00e1n llevando a cabo <strong>talleres formativos para familias<\/strong>, porque entendemos que es necesario que la escuela y la familia trabajen de la mano en esta gran tarea que es la educaci\u00f3n de la infancia.<\/p>\n<h3>El proyecto<\/h3>\n<p>Nuestro planeta pide socorro por el abuso y el maltrato que sufre, y las decisiones que tomemos en los pr\u00f3ximos a\u00f1os decidir\u00e1n su futuro. Nuestros peques son una <strong>nueva generaci\u00f3n ilusionada y entusiasta<\/strong>, que es muy capaz de trabajar juntos por el <strong>cuidado del medio ambiente.<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_video src=\u00bbhttps:\/\/youtu.be\/cxDH7qkYqmM\u00bb _builder_version=\u00bb4.3.4&#8243;][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb3_5,2_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.3.4&#8243; text_orientation=\u00bbjustified\u00bb border_style=\u00bbsolid\u00bb]<\/p>\n<p>Nuestro centro de inter\u00e9s ser\u00e1n los juegos. Sin duda, el juego es una <strong>buena herramienta metodol\u00f3gica<\/strong> para aprender y comprender la sociedad de hoy, as\u00ed pues pensamos que deber\u00eda estar m\u00e1s presente en las aulas, deber\u00eda ayudar a los ni\u00f1os a relacionar los conceptos trabajados desde las \u00e1reas curriculares y de la sociedad que les rodea.<\/p>\n<p>A trav\u00e9s de los juegos, intentaremos que nuestros alumnos se involucren en el <strong>cuidado del medio ambiente social y natural a partir de experiencias<\/strong>. Trataremos valores y conceptos como la globalizaci\u00f3n, la interculturalidad, el g\u00e9nero y la coeducaci\u00f3n, habilidades de pensamiento cr\u00edtico y creativo, estilos de vida y consumo sostenibles, participaci\u00f3n y democracia.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_image src=\u00bbhttps:\/\/triana.salesianos.edu\/wp-content\/uploads\/2020\/03\/20200304_ProyectoJuegosInfantil_9.jpeg\u00bb _builder_version=\u00bb4.3.4&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.0.6&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.3.4&#8243; text_orientation=\u00bbjustified\u00bb border_style=\u00bbsolid\u00bb]<\/p>\n<h3>El papel del juego<\/h3>\n<p>El juego constituye un <strong>elemento socializador e integrador<\/strong>. Favorece la comunicaci\u00f3n y la adquisici\u00f3n del lenguaje, adem\u00e1s facilita la <strong>integraci\u00f3n en la sociedad<\/strong>. Por otro lado, los juegos favorecen la <strong>aceptaci\u00f3n de la disciplina social<\/strong>, aceptando reglas comunes compartidas, desarrollan <strong>habilidades psicomotoras<\/strong> como ojo-mano, control postural, desarrollo cognitivo, social y afectivo, etc. Incluso permiten conocer el entorno en el que viven.<\/p>\n<p>Otras ventajas que ofrecen los juegos son el<strong> fomento de la ling\u00fc\u00edstica<\/strong> con un vocabulario espec\u00edfico. Permite que desarrollen el conocimiento sobre si mismos y el de los dem\u00e1s. <strong>Mejoran la autoestima.<\/strong> Lo importante es el juego, cooperaci\u00f3n, el tiempo y el placer que les produce.<\/p>\n<p>Los juegos multiculturales permitenn trabajar conceptos como la<strong> no discriminaci\u00f3n entre ni\u00f1os y ni\u00f1as de diferentes pa\u00edses del mundo.<\/strong> Adem\u00e1s, el conocimiento de otras culturas favorece el respeto por ellas y es beneficioso para ambas. De la misma manera, beneficia la comunicaci\u00f3n entre culturas y el enriquecimiento mutuo.<\/p>\n<h3>El resultado<\/h3>\n<p>El producto final de nuestro proyecto ha sido la realizaci\u00f3n de diversos juegos. Adem\u00e1s, el pasado 4 de marzo se invit\u00f3 a las familias a participar en las actividades junto con sus hijos, lo que ha contribuido a <strong>concienciar y valorar la importancia del cuidado del medio ambiente<\/strong> y la preservaci\u00f3n de los recursos naturales. Nuestras clases se transformaron en salas donde se expusieron los distintos juegos por parte del alumnado y que los explicaron a sus familiares.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb2_5,3_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_image src=\u00bbhttps:\/\/triana.salesianos.edu\/wp-content\/uploads\/2020\/03\/20200304_ProyectoJuegosInfantil_10.jpeg\u00bb _builder_version=\u00bb4.3.4&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.3.4&#8243; text_orientation=\u00bbjustified\u00bb border_style=\u00bbsolid\u00bb]<\/p>\n<p>En la primera de las salas se explic\u00f3 la din\u00e1mica a seguir, para despu\u00e9s encontrarse un tipo de juego diferente en cada aula. En la clase de 3 a\u00f1os A se mostraron <strong>juegos tradicionales y de dramatizaci\u00f3n<\/strong>, mientras que en la de 3 a\u00f1os B fueron<strong> juegos constructivos y manipulativos<\/strong>. A su vez, los chicos de 4 a\u00f1os A ofrecieron <strong>juegos mot\u00f3ricos e interculturales<\/strong>, siendo los de 4 a\u00f1os B<strong> juegos de creados a partir de materiales reciclados y juegos antiguos<\/strong>. Por \u00faltimo, en 5 a\u00f1os A se expusieron <strong>juegos cooperativos y simb\u00f3licos<\/strong>, para terminar con<strong> juegos de mesa y de patio<\/strong> en 5 a\u00f1os B.<\/p>\n<p>La visita termin\u00f3 en nuestro patio interior donde los visitantes pudieron disfrutar de una exposici\u00f3n de los diferentes juegos realizados por nuestr@s alumn@s .<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.3.4&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.3.4&#8243;][et_pb_text _builder_version=\u00bb4.3.4&#8243; hover_enabled=\u00bb0&#8243;]<\/p>\n\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En nuestro colegio creemos que nuestra escuela debe buscar la forma de contribuir a que el mundo en el que vivimos sea un lugar m\u00e1s justo y sostenible. Por eso en la etapa de Educaci\u00f3n Infantil estamos desarrollando un programa que se llama \u201c\u00c9rase una vez una escuela para el Mundo\u201d en colaboraci\u00f3n con la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9070,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[27,14,16],"tags":[],"class_list":["post-9074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colegio","category-infantil","category-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Infantil aprende jugando - Colegio Salesiano San Pedro<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Infantil aprende jugando - Colegio Salesiano San Pedro\" \/>\n<meta property=\"og:description\" content=\"En nuestro colegio creemos que nuestra escuela debe buscar la forma de contribuir a que el mundo en el que vivimos sea un lugar m\u00e1s justo y sostenible. Por eso en la etapa de Educaci\u00f3n Infantil estamos desarrollando un programa que se llama \u201c\u00c9rase una vez una escuela para el Mundo\u201d en colaboraci\u00f3n con la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/03\/05\/infantil-aprende-jugando\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Salesiano San Pedro\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-05T19:27:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-29T09:36:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/03\/20200304_ProyectoJuegosInfantil_2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestor Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestor Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/03\\\/05\\\/infantil-aprende-jugando\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/03\\\/05\\\/infantil-aprende-jugando\\\/\"},\"author\":{\"name\":\"Gestor Web\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac56d09b53320706efba5d42fa54fa77\"},\"headline\":\"Infantil aprende jugando\",\"datePublished\":\"2020-03-05T19:27:25+00:00\",\"dateModified\":\"2023-11-29T09:36:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/03\\\/05\\\/infantil-aprende-jugando\\\/\"},\"wordCount\":993,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/03\\\/05\\\/infantil-aprende-jugando\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/20200304_ProyectoJuegosInfantil_2.jpeg\",\"articleSection\":[\"Colegio\",\"Infantil\",\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/03\\\/05\\\/infantil-aprende-jugando\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/03\\\/05\\\/infantil-aprende-jugando\\\/\",\"url\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/03\\\/05\\\/infantil-aprende-jugando\\\/\",\"name\":\"Infantil aprende jugando - Colegio Salesiano San Pedro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/03\\\/05\\\/infantil-aprende-jugando\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/03\\\/05\\\/infantil-aprende-jugando\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/20200304_ProyectoJuegosInfantil_2.jpeg\",\"datePublished\":\"2020-03-05T19:27:25+00:00\",\"dateModified\":\"2023-11-29T09:36:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac56d09b53320706efba5d42fa54fa77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/03\\\/05\\\/infantil-aprende-jugando\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/03\\\/05\\\/infantil-aprende-jugando\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/03\\\/05\\\/infantil-aprende-jugando\\\/#primaryimage\",\"url\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/20200304_ProyectoJuegosInfantil_2.jpeg\",\"contentUrl\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/20200304_ProyectoJuegosInfantil_2.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/03\\\/05\\\/infantil-aprende-jugando\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Infantil aprende jugando\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Salesiano San Pedro\",\"description\":\"P\u00e1gina oficial Salesianos Triana Sevilla\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac56d09b53320706efba5d42fa54fa77\",\"name\":\"Gestor Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g\",\"caption\":\"Gestor Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Infantil aprende jugando - Colegio Salesiano San Pedro","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Infantil aprende jugando - Colegio Salesiano San Pedro","og_description":"En nuestro colegio creemos que nuestra escuela debe buscar la forma de contribuir a que el mundo en el que vivimos sea un lugar m\u00e1s justo y sostenible. Por eso en la etapa de Educaci\u00f3n Infantil estamos desarrollando un programa que se llama \u201c\u00c9rase una vez una escuela para el Mundo\u201d en colaboraci\u00f3n con la [&hellip;]","og_url":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/03\/05\/infantil-aprende-jugando\/","og_site_name":"Colegio Salesiano San Pedro","article_published_time":"2020-03-05T19:27:25+00:00","article_modified_time":"2023-11-29T09:36:02+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/03\/20200304_ProyectoJuegosInfantil_2.jpeg","type":"image\/jpeg"}],"author":"Gestor Web","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gestor Web","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/03\/05\/infantil-aprende-jugando\/#article","isPartOf":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/03\/05\/infantil-aprende-jugando\/"},"author":{"name":"Gestor Web","@id":"https:\/\/triana.salesianos.edu\/colegio\/#\/schema\/person\/ac56d09b53320706efba5d42fa54fa77"},"headline":"Infantil aprende jugando","datePublished":"2020-03-05T19:27:25+00:00","dateModified":"2023-11-29T09:36:02+00:00","mainEntityOfPage":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/03\/05\/infantil-aprende-jugando\/"},"wordCount":993,"commentCount":0,"image":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/03\/05\/infantil-aprende-jugando\/#primaryimage"},"thumbnailUrl":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/03\/20200304_ProyectoJuegosInfantil_2.jpeg","articleSection":["Colegio","Infantil","Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/03\/05\/infantil-aprende-jugando\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/03\/05\/infantil-aprende-jugando\/","url":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/03\/05\/infantil-aprende-jugando\/","name":"Infantil aprende jugando - Colegio Salesiano San Pedro","isPartOf":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/03\/05\/infantil-aprende-jugando\/#primaryimage"},"image":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/03\/05\/infantil-aprende-jugando\/#primaryimage"},"thumbnailUrl":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/03\/20200304_ProyectoJuegosInfantil_2.jpeg","datePublished":"2020-03-05T19:27:25+00:00","dateModified":"2023-11-29T09:36:02+00:00","author":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/#\/schema\/person\/ac56d09b53320706efba5d42fa54fa77"},"breadcrumb":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/03\/05\/infantil-aprende-jugando\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/03\/05\/infantil-aprende-jugando\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/03\/05\/infantil-aprende-jugando\/#primaryimage","url":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/03\/20200304_ProyectoJuegosInfantil_2.jpeg","contentUrl":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/03\/20200304_ProyectoJuegosInfantil_2.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/03\/05\/infantil-aprende-jugando\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/triana.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Infantil aprende jugando"}]},{"@type":"WebSite","@id":"https:\/\/triana.salesianos.edu\/colegio\/#website","url":"https:\/\/triana.salesianos.edu\/colegio\/","name":"Colegio Salesiano San Pedro","description":"P\u00e1gina oficial Salesianos Triana Sevilla","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/triana.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/triana.salesianos.edu\/colegio\/#\/schema\/person\/ac56d09b53320706efba5d42fa54fa77","name":"Gestor Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g","caption":"Gestor Web"}}]}},"_links":{"self":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/9074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=9074"}],"version-history":[{"count":1,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/9074\/revisions"}],"predecessor-version":[{"id":9075,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/9074\/revisions\/9075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/9070"}],"wp:attachment":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=9074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=9074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=9074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}