{"id":8987,"date":"2020-02-18T08:00:59","date_gmt":"2020-02-17T17:41:33","guid":{"rendered":"https:\/\/triana.salesianos.edu\/colegio\/?p=8987"},"modified":"2023-11-29T10:36:03","modified_gmt":"2023-11-29T09:36:03","slug":"el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo","status":"publish","type":"post","link":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/02\/18\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\/","title":{"rendered":"El voluntariado en Salesianos Triana se llama #CuentaConmigo"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb3.22&#8243;][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb3.25&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbEntradilla (Texto)\u00bb _builder_version=\u00bb4.0.6&#8243; text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb border_style=\u00bbsolid\u00bb]<\/p>\n<p><strong><em>El proyecto #<\/em>CuentaConmigo <em>es la nueva propuesta de la casa para canalizar las acciones de voluntariado de los miembros de la comunidad educativa. Varias entidades colaboran con el proyecto acogiendo voluntarios en sus actividades.<\/em><\/strong><\/p>\n<p><!--more--><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.0.6&#8243; text_orientation=\u00bbjustified\u00bb border_style=\u00bbsolid\u00bb]<\/p>\n<p>Enmarcado dentro del<strong> Plan Estrat\u00e9gico 2015-2021<\/strong>, entre las acciones que corresponden a la l\u00ednea Estrat\u00e9gica de Pastoral, en este curso ha echado a rodar en nuestra casa el proyecto <em>#CuentaConmigo<\/em>. Gracias a \u00e9l son <strong>m\u00e1s de 40 voluntarios<\/strong>, entre alumnos y profesores, los que en breve comenzar\u00e1n a trabajar en diferentes organizaciones.<\/p>\n<p>El objetivo de este nuevo proyecto es proporcionar a los miembros de la comunidad educativa, especialmente el alumnado mayor de 16 a\u00f1os, una <strong>experiencia aut\u00e9ntica de ayuda a los dem\u00e1s<\/strong>. De esta manera, podr\u00e1n vivir en primera persona el <strong>compromiso evang\u00e9lico de ayuda al necesitado<\/strong> al mismo tiempo que podr\u00e1n sentir un notable <strong>crecimiento personal.<\/strong><\/p>\n<p>Siguiendo el esp\u00edritu del <strong><em>#SomosUno<\/em><\/strong>, lema inspectorial para este curso, este camino <strong>no lo viven solos nuestros alumnos<\/strong>, sino que un grupo de <strong>profesores voluntarios<\/strong> los acompa\u00f1ar\u00e1n en cada una de las experiencias. De esta manera podemos comprobar que, a la hora de construir el Reino de Dios,\u00a0<strong>todos estamos llamados y somos iguales<\/strong>\u00a0unos a otros.<\/p>\n<h3><strong><em>El arranque del proyecto<\/em><\/strong><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb3_5,2_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.0.6&#8243; text_orientation=\u00bbjustified\u00bb border_style=\u00bbsolid\u00bb]<\/p>\n<p>El camino recorrido durante este curso hasta llegar al momento actual ha estado plagado de peque\u00f1os pasos. En un primer momento hubo que buscar las entidades en las que colaborar\u00e1n nuestros voluntarios, para posteriormente presentar estas experiencias tanto al alumnado como al profesorado en sendas <strong>mesas redondas<\/strong> que tuvieron lugar en el primer trimestre.<\/p>\n<p>Una vez conocidas las opciones, se dio lugar a que los voluntarios se inscribieran en el proyecto y expresaran sus campos de trabajo preferentes. Tras unas semanas de organizaci\u00f3n, el pasado viernes 14 de febrero, los voluntarios vivieron una bella tarde de <strong>convivencia de lanzamiento<\/strong> en la que tuvieron un breve <strong>momento de formaci\u00f3n y una emotiva Celebraci\u00f3n del Env\u00edo.<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_image src=\u00bbhttps:\/\/triana.salesianos.edu\/wp-content\/uploads\/2020\/02\/foto2.jpg\u00bb _builder_version=\u00bb4.0.6&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.0.6&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.0.6&#8243; text_orientation=\u00bbjustified\u00bb border_style=\u00bbsolid\u00bb]<\/p>\n<h3><strong><em>Las entidades colaboradoras<\/em><\/strong><\/h3>\n<p>Han sido varios los proyectos que, tras una ardua b\u00fasqueda, han sido seleccionados para acoger a nuestros voluntarios. As\u00ed, destacan los proyectos de la bolsa de caridad de la <strong>Hermandad del Roc\u00edo de Triana<\/strong>, el economato y el comedor que las <strong>Hermanas de la Caridad<\/strong> disponen en Triana y la<strong> Ciudad de San Juan de Dios<\/strong>, de la orden hom\u00f3nima en Alcal\u00e1 de Guadaira.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb2_5,3_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_image src=\u00bbhttps:\/\/triana.salesianos.edu\/wp-content\/uploads\/2020\/02\/foto3.jpg\u00bb _builder_version=\u00bb4.0.6&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.0.6&#8243;][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.0.6&#8243; text_orientation=\u00bbjustified\u00bb border_style=\u00bbsolid\u00bb]<\/p>\n<p>Tambi\u00e9n acudir\u00e1n voluntarios al <strong>Oratorio Tres Barrios<\/strong> que llevan los Salesianos Cooperadores en la <strong>Parroquia de la Blanca Paloma en el barrio de los Pajaritos<\/strong>. Para quien prefiera un trabajo m\u00e1s cercano, tambi\u00e9n se han ofrecido actividades de nuestra propia casa, como son el<strong> Oratorio-Centro Juvenil Eiren\u00e9<\/strong> y el proyecto <strong><em>Para Sumar<\/em> <\/strong>de clases de apoyo.<\/p>\n<p>Desde estas l\u00edneas, no nos queda otra que desearle todo lo mejor a estos valientes voluntarios que se pondr\u00e1n manos a la obra de manera inminente, y <strong>rezarle a Mar\u00eda Auxiliadora para que los acompa\u00f1e<\/strong> en su trabajo por los dem\u00e1s.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proyecto #CuentaConmigo es la nueva propuesta de la casa para canalizar las acciones de voluntariado de los miembros de la comunidad educativa. Varias entidades colaboran con el proyecto acogiendo voluntarios en sus actividades. Enmarcado dentro del Plan Estrat\u00e9gico 2015-2021, entre las acciones que corresponden a la l\u00ednea Estrat\u00e9gica de Pastoral, en este curso ha [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8988,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[32,27,16],"tags":[],"class_list":["post-8987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-centro-juvenil","category-colegio","category-portada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El voluntariado en Salesianos Triana se llama #CuentaConmigo - Colegio Salesiano San Pedro<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El voluntariado en Salesianos Triana se llama #CuentaConmigo - Colegio Salesiano San Pedro\" \/>\n<meta property=\"og:description\" content=\"El proyecto #CuentaConmigo es la nueva propuesta de la casa para canalizar las acciones de voluntariado de los miembros de la comunidad educativa. Varias entidades colaboran con el proyecto acogiendo voluntarios en sus actividades. Enmarcado dentro del Plan Estrat\u00e9gico 2015-2021, entre las acciones que corresponden a la l\u00ednea Estrat\u00e9gica de Pastoral, en este curso ha [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/02\/17\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Salesiano San Pedro\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-17T17:41:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-29T09:36:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/02\/foto1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestor Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestor Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/02\\\/17\\\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/02\\\/17\\\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\\\/\"},\"author\":{\"name\":\"Gestor Web\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac56d09b53320706efba5d42fa54fa77\"},\"headline\":\"El voluntariado en Salesianos Triana se llama #CuentaConmigo\",\"datePublished\":\"2020-02-17T17:41:33+00:00\",\"dateModified\":\"2023-11-29T09:36:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/02\\\/17\\\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\\\/\"},\"wordCount\":765,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/02\\\/17\\\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/foto1.jpg\",\"articleSection\":[\"Centro Juvenil\",\"Colegio\",\"Portada\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/02\\\/17\\\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/02\\\/17\\\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\\\/\",\"url\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/02\\\/17\\\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\\\/\",\"name\":\"El voluntariado en Salesianos Triana se llama #CuentaConmigo - Colegio Salesiano San Pedro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/02\\\/17\\\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/02\\\/17\\\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/foto1.jpg\",\"datePublished\":\"2020-02-17T17:41:33+00:00\",\"dateModified\":\"2023-11-29T09:36:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac56d09b53320706efba5d42fa54fa77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/02\\\/17\\\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/02\\\/17\\\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/02\\\/17\\\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/foto1.jpg\",\"contentUrl\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/foto1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/02\\\/17\\\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El voluntariado en Salesianos Triana se llama #CuentaConmigo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Salesiano San Pedro\",\"description\":\"P\u00e1gina oficial Salesianos Triana Sevilla\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac56d09b53320706efba5d42fa54fa77\",\"name\":\"Gestor Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g\",\"caption\":\"Gestor Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El voluntariado en Salesianos Triana se llama #CuentaConmigo - Colegio Salesiano San Pedro","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"El voluntariado en Salesianos Triana se llama #CuentaConmigo - Colegio Salesiano San Pedro","og_description":"El proyecto #CuentaConmigo es la nueva propuesta de la casa para canalizar las acciones de voluntariado de los miembros de la comunidad educativa. Varias entidades colaboran con el proyecto acogiendo voluntarios en sus actividades. Enmarcado dentro del Plan Estrat\u00e9gico 2015-2021, entre las acciones que corresponden a la l\u00ednea Estrat\u00e9gica de Pastoral, en este curso ha [&hellip;]","og_url":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/02\/17\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\/","og_site_name":"Colegio Salesiano San Pedro","article_published_time":"2020-02-17T17:41:33+00:00","article_modified_time":"2023-11-29T09:36:03+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/02\/foto1.jpg","type":"image\/jpeg"}],"author":"Gestor Web","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gestor Web","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/02\/17\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\/#article","isPartOf":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/02\/17\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\/"},"author":{"name":"Gestor Web","@id":"https:\/\/triana.salesianos.edu\/colegio\/#\/schema\/person\/ac56d09b53320706efba5d42fa54fa77"},"headline":"El voluntariado en Salesianos Triana se llama #CuentaConmigo","datePublished":"2020-02-17T17:41:33+00:00","dateModified":"2023-11-29T09:36:03+00:00","mainEntityOfPage":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/02\/17\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\/"},"wordCount":765,"commentCount":0,"image":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/02\/17\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\/#primaryimage"},"thumbnailUrl":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/02\/foto1.jpg","articleSection":["Centro Juvenil","Colegio","Portada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/02\/17\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/02\/17\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\/","url":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/02\/17\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\/","name":"El voluntariado en Salesianos Triana se llama #CuentaConmigo - Colegio Salesiano San Pedro","isPartOf":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/02\/17\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\/#primaryimage"},"image":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/02\/17\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\/#primaryimage"},"thumbnailUrl":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/02\/foto1.jpg","datePublished":"2020-02-17T17:41:33+00:00","dateModified":"2023-11-29T09:36:03+00:00","author":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/#\/schema\/person\/ac56d09b53320706efba5d42fa54fa77"},"breadcrumb":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/02\/17\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/02\/17\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/02\/17\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\/#primaryimage","url":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/02\/foto1.jpg","contentUrl":"https:\/\/triana.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/02\/foto1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2020\/02\/17\/el-voluntariado-en-salesianos-triana-se-llama-cuentaconmigo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/triana.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"El voluntariado en Salesianos Triana se llama #CuentaConmigo"}]},{"@type":"WebSite","@id":"https:\/\/triana.salesianos.edu\/colegio\/#website","url":"https:\/\/triana.salesianos.edu\/colegio\/","name":"Colegio Salesiano San Pedro","description":"P\u00e1gina oficial Salesianos Triana Sevilla","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/triana.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/triana.salesianos.edu\/colegio\/#\/schema\/person\/ac56d09b53320706efba5d42fa54fa77","name":"Gestor Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g","caption":"Gestor Web"}}]}},"_links":{"self":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/8987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=8987"}],"version-history":[{"count":2,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/8987\/revisions"}],"predecessor-version":[{"id":8991,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/8987\/revisions\/8991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/8988"}],"wp:attachment":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=8987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=8987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=8987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}