{"id":24641,"date":"2024-02-01T14:08:59","date_gmt":"2024-02-01T13:08:59","guid":{"rendered":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2024\/02\/01\/triana-sono-con-don-bosco-un-ano-mas\/"},"modified":"2024-02-01T14:08:59","modified_gmt":"2024-02-01T13:08:59","slug":"triana-sono-con-don-bosco-un-ano-mas","status":"publish","type":"post","link":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2024\/02\/01\/triana-sono-con-don-bosco-un-ano-mas\/","title":{"rendered":"Triana so\u00f1\u00f3 con Don Bosco un a\u00f1o m\u00e1s"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb admin_label=\u00bbSecci\u00f3n\u00bb _builder_version=\u00bb4.24.2&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_header title=\u00bbTriana so\u00f1\u00f3 con Don Bosco un a\u00f1o m\u00e1s\u00bb content_max_width=\u00bbnone\u00bb title_font_color=\u00bb#ffffff\u00bb admin_label=\u00bbT\u00edtulo de anchura completa\u00bb module_class=\u00bbpagina-imagen-cabecera\u00bb _builder_version=\u00bb4.24.2&#8243; title_text_color=\u00bb#ffffff\u00bb title_font_size=\u00bb40px\u00bb background_color=\u00bbrgba(255, 255, 255, 0)\u00bb background_image=\u00bbhttps:\/\/triana.salesianos.edu\/wp-content\/uploads\/2024\/04\/Don-Bosco-24-20-scaled.jpg\u00bb background_layout=\u00bblight\u00bb min_height=\u00bb281px\u00bb background_url=\u00bbhttp:\/\/webpiloto.salesianos.edu\/wp-content\/uploads\/2017\/02\/ImagenPAGINA01.png\u00bb button_one_letter_spacing_hover=\u00bb0&#8243; button_two_letter_spacing_hover=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bbon\u00bb button_one_letter_spacing__hover=\u00bb0&#8243; button_two_letter_spacing__hover_enabled=\u00bbon\u00bb button_two_letter_spacing__hover=\u00bb0&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbSecci\u00f3n\u00bb module_class=\u00bbpagina-seccion-contenido\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb-4%|||\u00bb transparent_background=\u00bboff\u00bb make_fullwidth=\u00bboff\u00bb use_custom_width=\u00bboff\u00bb width_unit=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbFila\u00bb module_class=\u00bbpagina-texto\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb make_fullwidth=\u00bboff\u00bb use_custom_width=\u00bboff\u00bb width_unit=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbTexto\u00bb _builder_version=\u00bb4.24.2&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb use_border_color=\u00bboff\u00bb border_color=\u00bb#ffffff\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Celebraciones durante el mes<\/h2>\n<p>Un a\u00f1o m\u00e1s, nuestra casa ha vivido un mes de enero lleno de actividad y entrega total conmemorando a nuestro fundador, San Juan Bosco. Al m\u00e1s puro estilo salesiano, combinando lo acad\u00e9mico con lo festivo y lo religioso, toda nuestra casa se ha llenado de actividades y momentos en torno a la figura del santo de la juventud.<\/p>\n<p>El mes daba comienzo con los preparativos del 36\u00ba festival de playbacks de nuestra casa que, debido a la afluencia de grupos participantes, modific\u00f3 su estructura para pasar a tener tres finales: primaria, ESO (1\u00ba a 3\u00ba) y la \u00faltima categor\u00eda con los cursos superiores: 4\u00ba de ESO, Bachillerato y Formaci\u00f3n Profesional. Sin duda ha sido una actividad muy seguida por toda la casa, tanto en vivo como en las retransmisiones en redes sociales.<\/p>\n<p>Por supuesto tampoco han faltado otras m\u00faltiples actividades: talleres, competiciones deportivas (f\u00fatbol, baloncesto, voleibol\u2026), karaoke, baile, talleres gastron\u00f3micos y un sinf\u00edn de posibilidades que han permitido que nuestros alumnos celebren desde un ambiente sano y festivo la fiesta de San Juan Bosco.<\/p>\n<p>Tambi\u00e9n cobr\u00f3 mucha importancia la celebraci\u00f3n religiosa, con la celebraci\u00f3n del triduo en nuestra parroquia los d\u00edas previos a la fiesta. En concreto, la celebraci\u00f3n de los d\u00edas del triduo estuvo a cargo de los salesianos de la comunidad de nuestra casa: D. Carlos Correas, D. Manuel Anselmo Tom\u00e9 y D. Francisco Jos\u00e9 P\u00e9rez. Paralelamente, los d\u00edas lectivos previos, todos los alumnos de nuestro colegio tambi\u00e9n celebraron su particular triduo, adaptado a las diferentes edades.<\/p>\n<h2>El d\u00eda 31&#8230;<\/h2>\n<p>La llegada del d\u00eda 31 fue muy emotiva en la casa. En primer lugar, con la celebraci\u00f3n de la eucarist\u00eda escolar que cont\u00f3, adem\u00e1s de con todo el alumnado y profesorado del centro, con una afluencia muy concurrida de antiguos alumnos que dejan constancia de que el sue\u00f1o de Don Bosco sigue vivo y a\u00fan hoy late con fuerza en cada uno de sus corazones. Posteriormente, las etapas educativas celebraron el d\u00eda con las competiciones de juegos oratorianos, en un ambiente emotivo, l\u00fadico y muy festivo.<\/p>\n<p>Por la tarde, el punto y final a la fiesta lo tuvo la celebraci\u00f3n de la funci\u00f3n solemne en honor a nuestro fundador. Este a\u00f1o ha sido presidida por D. Ram\u00f3n Valdivia Gim\u00e9nez, Obispo Auxiliar de nuestra Archidi\u00f3cesis de Sevilla.<\/p>\n<h2><span style=\"color: #dc001b;\"><strong>Galer\u00eda de fotos<\/strong><\/span><\/h2>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=\u00bb65233,65213,65232,65231,65230,65229,65228,65227,65226,65225,65224,65223,65222,65221,65220,65219,65218,65217,65216,65215,65214&#8243; _builder_version=\u00bb4.24.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Celebraciones durante el mes Un a\u00f1o m\u00e1s, nuestra casa ha vivido un mes de enero lleno de actividad y entrega total conmemorando a nuestro fundador, San Juan Bosco. Al m\u00e1s puro estilo salesiano, combinando lo acad\u00e9mico con lo festivo y lo religioso, toda nuestra casa se ha llenado de actividades y momentos en torno a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30,32,27,40,16,34,33,1],"tags":[],"class_list":["post-24641","post","type-post","status-publish","format-standard","hentry","category-ampa","category-centro-juvenil","category-colegio","category-parroquia","category-portada","category-portada-imagen","category-solidaridad","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Triana so\u00f1\u00f3 con Don Bosco un a\u00f1o m\u00e1s - Colegio Salesiano San Pedro<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Triana so\u00f1\u00f3 con Don Bosco un a\u00f1o m\u00e1s - Colegio Salesiano San Pedro\" \/>\n<meta property=\"og:description\" content=\"Celebraciones durante el mes Un a\u00f1o m\u00e1s, nuestra casa ha vivido un mes de enero lleno de actividad y entrega total conmemorando a nuestro fundador, San Juan Bosco. Al m\u00e1s puro estilo salesiano, combinando lo acad\u00e9mico con lo festivo y lo religioso, toda nuestra casa se ha llenado de actividades y momentos en torno a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/triana.salesianos.edu\/colegio\/blog\/2024\/02\/01\/triana-sono-con-don-bosco-un-ano-mas\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Salesiano San Pedro\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-01T13:08:59+00:00\" \/>\n<meta name=\"author\" content=\"Gestor Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestor Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2024\\\/02\\\/01\\\/triana-sono-con-don-bosco-un-ano-mas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2024\\\/02\\\/01\\\/triana-sono-con-don-bosco-un-ano-mas\\\/\"},\"author\":{\"name\":\"Gestor Web\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac56d09b53320706efba5d42fa54fa77\"},\"headline\":\"Triana so\u00f1\u00f3 con Don Bosco un a\u00f1o m\u00e1s\",\"datePublished\":\"2024-02-01T13:08:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2024\\\/02\\\/01\\\/triana-sono-con-don-bosco-un-ano-mas\\\/\"},\"wordCount\":782,\"commentCount\":0,\"articleSection\":[\"AMPA\",\"Centro Juvenil\",\"Colegio\",\"Parroquia\",\"Portada\",\"Portada Imagen\",\"Solidaridad\",\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2024\\\/02\\\/01\\\/triana-sono-con-don-bosco-un-ano-mas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2024\\\/02\\\/01\\\/triana-sono-con-don-bosco-un-ano-mas\\\/\",\"url\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2024\\\/02\\\/01\\\/triana-sono-con-don-bosco-un-ano-mas\\\/\",\"name\":\"Triana so\u00f1\u00f3 con Don Bosco un a\u00f1o m\u00e1s - Colegio Salesiano San Pedro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#website\"},\"datePublished\":\"2024-02-01T13:08:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac56d09b53320706efba5d42fa54fa77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2024\\\/02\\\/01\\\/triana-sono-con-don-bosco-un-ano-mas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2024\\\/02\\\/01\\\/triana-sono-con-don-bosco-un-ano-mas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/blog\\\/2024\\\/02\\\/01\\\/triana-sono-con-don-bosco-un-ano-mas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Triana so\u00f1\u00f3 con Don Bosco un a\u00f1o m\u00e1s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Salesiano San Pedro\",\"description\":\"P\u00e1gina oficial Salesianos Triana Sevilla\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/triana.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ac56d09b53320706efba5d42fa54fa77\",\"name\":\"Gestor Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g\",\"caption\":\"Gestor Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Triana so\u00f1\u00f3 con Don Bosco un a\u00f1o m\u00e1s - Colegio Salesiano San Pedro","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Triana so\u00f1\u00f3 con Don Bosco un a\u00f1o m\u00e1s - Colegio Salesiano San Pedro","og_description":"Celebraciones durante el mes Un a\u00f1o m\u00e1s, nuestra casa ha vivido un mes de enero lleno de actividad y entrega total conmemorando a nuestro fundador, San Juan Bosco. Al m\u00e1s puro estilo salesiano, combinando lo acad\u00e9mico con lo festivo y lo religioso, toda nuestra casa se ha llenado de actividades y momentos en torno a [&hellip;]","og_url":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2024\/02\/01\/triana-sono-con-don-bosco-un-ano-mas\/","og_site_name":"Colegio Salesiano San Pedro","article_published_time":"2024-02-01T13:08:59+00:00","author":"Gestor Web","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gestor Web","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2024\/02\/01\/triana-sono-con-don-bosco-un-ano-mas\/#article","isPartOf":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2024\/02\/01\/triana-sono-con-don-bosco-un-ano-mas\/"},"author":{"name":"Gestor Web","@id":"https:\/\/triana.salesianos.edu\/colegio\/#\/schema\/person\/ac56d09b53320706efba5d42fa54fa77"},"headline":"Triana so\u00f1\u00f3 con Don Bosco un a\u00f1o m\u00e1s","datePublished":"2024-02-01T13:08:59+00:00","mainEntityOfPage":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2024\/02\/01\/triana-sono-con-don-bosco-un-ano-mas\/"},"wordCount":782,"commentCount":0,"articleSection":["AMPA","Centro Juvenil","Colegio","Parroquia","Portada","Portada Imagen","Solidaridad","Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/triana.salesianos.edu\/colegio\/blog\/2024\/02\/01\/triana-sono-con-don-bosco-un-ano-mas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2024\/02\/01\/triana-sono-con-don-bosco-un-ano-mas\/","url":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2024\/02\/01\/triana-sono-con-don-bosco-un-ano-mas\/","name":"Triana so\u00f1\u00f3 con Don Bosco un a\u00f1o m\u00e1s - Colegio Salesiano San Pedro","isPartOf":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/#website"},"datePublished":"2024-02-01T13:08:59+00:00","author":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/#\/schema\/person\/ac56d09b53320706efba5d42fa54fa77"},"breadcrumb":{"@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2024\/02\/01\/triana-sono-con-don-bosco-un-ano-mas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/triana.salesianos.edu\/colegio\/blog\/2024\/02\/01\/triana-sono-con-don-bosco-un-ano-mas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/triana.salesianos.edu\/colegio\/blog\/2024\/02\/01\/triana-sono-con-don-bosco-un-ano-mas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/triana.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Triana so\u00f1\u00f3 con Don Bosco un a\u00f1o m\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/triana.salesianos.edu\/colegio\/#website","url":"https:\/\/triana.salesianos.edu\/colegio\/","name":"Colegio Salesiano San Pedro","description":"P\u00e1gina oficial Salesianos Triana Sevilla","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/triana.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/triana.salesianos.edu\/colegio\/#\/schema\/person\/ac56d09b53320706efba5d42fa54fa77","name":"Gestor Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e89c91da47a7fb64ca5f65c45ef901e52d2b7a5c0f7eb1ae1e1c5f1e0c314da?s=96&d=mm&r=g","caption":"Gestor Web"}}]}},"_links":{"self":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/24641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=24641"}],"version-history":[{"count":0,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/24641\/revisions"}],"wp:attachment":[{"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=24641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=24641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/triana.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=24641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}